{"id":1,"count":3,"description":"","link":"http:\/\/ns2.serieguide.se\/en\/arkiv\/category\/uncategorized","name":"Uncategorized","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uncategorized-arkiv - Svenska Serieakademin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/193.44.159.78\/en\/arkiv\/category\/uncategorized\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/193.44.159.78\\\/en\\\/arkiv\\\/category\\\/uncategorized\",\"url\":\"http:\\\/\\\/193.44.159.78\\\/en\\\/arkiv\\\/category\\\/uncategorized\",\"name\":\"Uncategorized-arkiv - Svenska Serieakademin\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/193.44.159.78\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/193.44.159.78\\\/en\\\/arkiv\\\/category\\\/uncategorized#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/193.44.159.78\\\/en\\\/arkiv\\\/category\\\/uncategorized#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hem\",\"item\":\"http:\\\/\\\/193.44.159.78\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uncategorized\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/193.44.159.78\\\/#website\",\"url\":\"http:\\\/\\\/193.44.159.78\\\/\",\"name\":\"Svenska Serieakademin\",\"description\":\"Sk\u00e4mt och allvar\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/193.44.159.78\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uncategorized-arkiv - Svenska Serieakademin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/193.44.159.78\/en\/arkiv\/category\/uncategorized","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/193.44.159.78\/en\/arkiv\/category\/uncategorized","url":"http:\/\/193.44.159.78\/en\/arkiv\/category\/uncategorized","name":"Uncategorized-arkiv - Svenska Serieakademin","isPartOf":{"@id":"http:\/\/193.44.159.78\/#website"},"breadcrumb":{"@id":"http:\/\/193.44.159.78\/en\/arkiv\/category\/uncategorized#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"http:\/\/193.44.159.78\/en\/arkiv\/category\/uncategorized#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hem","item":"http:\/\/193.44.159.78\/"},{"@type":"ListItem","position":2,"name":"Uncategorized"}]},{"@type":"WebSite","@id":"http:\/\/193.44.159.78\/#website","url":"http:\/\/193.44.159.78\/","name":"Svenska Serieakademin","description":"Sk\u00e4mt och allvar","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/193.44.159.78\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"http:\/\/ns2.serieguide.se\/en\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/ns2.serieguide.se\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/ns2.serieguide.se\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/ns2.serieguide.se\/en\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}